{"id":1746,"date":"2026-04-09T16:25:27","date_gmt":"2026-04-09T14:25:27","guid":{"rendered":"https:\/\/zubnipececb.cz\/de\/poradna\/wie-oft-sollte-ich-zur-professionellen-zahnreinigung-gehen\/"},"modified":"2026-04-09T16:25:27","modified_gmt":"2026-04-09T14:25:27","slug":"wie-oft-sollte-ich-zur-professionellen-zahnreinigung-gehen","status":"publish","type":"dotaz","link":"https:\/\/zubnipececb.cz\/de\/anfrage\/wie-oft-sollte-ich-zur-professionellen-zahnreinigung-gehen\/","title":{"rendered":"Wie oft sollte ich zur professionellen Zahnreinigung gehen?"},"content":{"rendered":"<p>Wir empfehlen eine professionelle Zahnreinigung zweimal j\u00e4hrlich. Bei Patienten mit Parodontitis, Implantaten oder erh\u00f6htem Kariesrisiko kann ein k\u00fcrzeres Intervall (alle 3\u20134 Monate) sinnvoll sein.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir empfehlen eine professionelle Zahnreinigung zweimal j\u00e4hrlich. Bei Patienten mit Parodontitis, Implantaten oder erh\u00f6htem Kariesrisiko kann ein k\u00fcrzeres Intervall (alle 3\u20134 Monate) sinnvoll sein.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"categories":[68],"class_list":["post-1746","dotaz","type-dotaz","status-publish","hentry","category-dentalhygiene"],"acf":[],"_links":{"self":[{"href":"https:\/\/zubnipececb.cz\/de\/wp-json\/wp\/v2\/dotaz\/1746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zubnipececb.cz\/de\/wp-json\/wp\/v2\/dotaz"}],"about":[{"href":"https:\/\/zubnipececb.cz\/de\/wp-json\/wp\/v2\/types\/dotaz"}],"wp:attachment":[{"href":"https:\/\/zubnipececb.cz\/de\/wp-json\/wp\/v2\/media?parent=1746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zubnipececb.cz\/de\/wp-json\/wp\/v2\/categories?post=1746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}